{"id":76,"count":17,"description":"Une collection qui donne vie \u00e0 une faune stylis\u00e9e, pr\u00e9cieuse et pleine de caract\u00e8re.\r\nSuzon puise dans le r\u00e8gne animal pour imaginer des bijoux de bouton en forme de tortues, poissons ou coquillages, aux reflets dor\u00e9s et d\u00e9tails d\u00e9licats.\r\nUn clin d\u2019\u0153il malicieux \u00e0 la nature, pour des chemises qui ne manquent pas de piquant.","link":"https:\/\/lalogedesuzon.com\/it\/categoria-prodotto\/bijou-de-bouton-regne-animal\/","name":"Il Regno Animale","slug":"bijou-de-bouton-regne-animal","taxonomy":"product_cat","parent":0,"meta":{"order":["0"],"wcb2b_group_visibility":["a:2:{i:0;i:2195;i:1;i:2197;}"],"thumbnail_id":["0"],"display_type":[""],"_wc_facebook_google_product_category":[""],"_wc_facebook_enhanced_catalog_attributes___optional_selector":[null],"product_count_product_cat":["17"]},"menu_order":0,"_links":{"self":[{"href":"https:\/\/lalogedesuzon.com\/it\/wp-json\/wp\/v2\/product_cat\/76","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lalogedesuzon.com\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/lalogedesuzon.com\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/lalogedesuzon.com\/it\/wp-json\/wp\/v2\/product?product_cat=76"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}